{"id":15,"date":"2021-08-24T17:54:43","date_gmt":"2021-08-24T17:54:43","guid":{"rendered":"https:\/\/baumschnitt-ja.de\/?page_id=15"},"modified":"2021-08-27T22:10:38","modified_gmt":"2021-08-27T22:10:38","slug":"impressum","status":"publish","type":"page","link":"https:\/\/baumschnitt-ja.de\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15\" class=\"elementor elementor-15\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e91737b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e91737b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f93f41\" data-id=\"3f93f41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f367e8f elementor-widget elementor-widget-heading\" data-id=\"f367e8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 17-10-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Impressum<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d7b75b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d7b75b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30120189\" data-id=\"30120189\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c11f27a elementor-widget elementor-widget-text-editor\" data-id=\"2c11f27a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 17-10-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Angaben gem\u00e4\u00df \u00a7 5 TMG:<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\">Jeremias Aigner <br \/>Gartenmanufaktur Bouleau <br \/>Tannenweg 26 <br \/>93333 Neustadt\/Donau <\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Kontakt:<\/strong> <br \/>Telefon: +4915901322944 <br \/>Mail: gartenmanufaktur-bouleau [\u00e4t] posteo [punkt] de<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Haftungsausschluss (Disclaimer)<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Haftung f\u00fcr Inhalte<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\">Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen. Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Haftung f\u00fcr Links<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\">Unser Angebot enth\u00e4lt Links zu externen Webseiten Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar. Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><strong>Urheberrecht<\/strong><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\">Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet. Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\"><a href=\"https:\/\/baumschnitt-ja.de\/index.php\/privacy-policy\/\"><strong>Datenschutz<\/strong><\/a><\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph {\"style\":{\"typography\":{\"fontSize\":\"11px\"}}} -->\n<p style=\"font-size: 11px;\">Der <a href=\"https:\/\/baumschnitt-ja.de\/index.php\/privacy-policy\/\">Datenschutz<\/a> ist dem Anbieter dieser Website ein besonderes Anliegen, weshalb auf einer eigenen Seite ausf\u00fchrliche darauf eingegangen wird.<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG: Jeremias Aigner Gartenmanufaktur Bouleau Tannenweg 26 93333 Neustadt\/Donau Kontakt: Telefon: +4915901322944 Mail: gartenmanufaktur-bouleau [\u00e4t] posteo [punkt] de Haftungsausschluss (Disclaimer) Haftung f\u00fcr Inhalte Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":10,"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/pages\/15\/revisions\/178"}],"wp:attachment":[{"href":"https:\/\/baumschnitt-ja.de\/index.php\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}